{"id":13075,"date":"2024-05-18T09:57:55","date_gmt":"2024-05-18T13:57:55","guid":{"rendered":"https:\/\/autoazulplusca.com\/puertoordaz\/?post_type=product&#038;p=13075"},"modified":"2025-05-24T16:30:22","modified_gmt":"2025-05-24T20:30:22","slug":"casco-sport-semi-integral-gmi-c-blanco-turquesa","status":"publish","type":"product","link":"https:\/\/autoazulplusca.com\/puertoordaz\/product\/casco-sport-semi-integral-gmi-c-blanco-turquesa\/","title":{"rendered":"Casco Sport Semi Integral GMI C\/Blanco-Turquesa"},"content":{"rendered":"<p>Casco Sport Semi Integral GMI C\/Blanco-Turquesa SB02TBL<\/p>\n<p>COD 24837<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Casco Sport Semi Integral GMI C\/Blanco-Turquesa SB02TBL<\/p>\n","protected":false},"featured_media":13077,"template":"","meta":[],"product_brand":[440],"product_cat":[352],"product_tag":[439],"class_list":["post-13075","product","type-product","status-publish","has-post-thumbnail","product_brand-gmi","product_cat-accesorios-moto","product_tag-casco","first","outofstock","taxable","shipping-taxable","purchasable","product-type-simple"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/autoazulplusca.com\/puertoordaz\/wp-json\/wp\/v2\/product\/13075","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/autoazulplusca.com\/puertoordaz\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/autoazulplusca.com\/puertoordaz\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/autoazulplusca.com\/puertoordaz\/wp-json\/wp\/v2\/media\/13077"}],"wp:attachment":[{"href":"https:\/\/autoazulplusca.com\/puertoordaz\/wp-json\/wp\/v2\/media?parent=13075"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/autoazulplusca.com\/puertoordaz\/wp-json\/wp\/v2\/product_brand?post=13075"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/autoazulplusca.com\/puertoordaz\/wp-json\/wp\/v2\/product_cat?post=13075"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/autoazulplusca.com\/puertoordaz\/wp-json\/wp\/v2\/product_tag?post=13075"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}